{"id":68,"date":"2017-10-02T00:40:46","date_gmt":"2017-10-01T22:40:46","guid":{"rendered":"http:\/\/pmfeenix-conseil.fr\/site\/?page_id=68"},"modified":"2017-10-02T00:40:46","modified_gmt":"2017-10-01T22:40:46","slug":"qui-suis-je","status":"publish","type":"page","link":"https:\/\/pascalinematusiak.fr\/","title":{"rendered":"Qui suis-je"},"content":{"rendered":"<h1><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-46 alignleft\" src=\"http:\/\/pmfeenix-conseil.fr\/site\/wp-content\/uploads\/2017\/02\/Pascaline-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/pascalinematusiak.fr\/wp-content\/uploads\/2017\/02\/Pascaline-300x300.jpg 300w, https:\/\/pascalinematusiak.fr\/wp-content\/uploads\/2017\/02\/Pascaline-150x150.jpg 150w, https:\/\/pascalinematusiak.fr\/wp-content\/uploads\/2017\/02\/Pascaline-301x300.jpg 301w, https:\/\/pascalinematusiak.fr\/wp-content\/uploads\/2017\/02\/Pascaline.jpg 327w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><strong>Pascaline MATUSIAK<\/strong><\/h1>\n<p style=\"padding-left: 40px;\">\u21d2 Souhaitant m\u2019inscrire dans la lign\u00e9e familiale, je me suis initialement engag\u00e9e dans des \u00e9tudes qui m\u2019auraient conduite \u00e0 enseigner l\u2019Histoire en obtenant une ma\u00eetrise d\u2019Histoire moderne et en pr\u00e9parant le CAPES d\u2019Histoire-G\u00e9ographie.<\/p>\n<p style=\"padding-left: 40px;\">Dans un contexte o\u00f9 je me suis interrog\u00e9e sur mon devenir professionnel j\u2019ai int\u00e9gr\u00e9 successivement plusieurs entreprises en tant que conseill\u00e8re commerciale puis formatrice et manager m\u2019amenant \u00e0 g\u00e9rer plusieurs business units dans des domaines d\u2019activit\u00e9s vari\u00e9s.<\/p>\n<p><br \/>C\u2019est alors que j\u2019ai r\u00e9alis\u00e9 en 2003 que le bien-\u00eatre \u00e9tait une notion dont on parlait peu. J\u2019ai ainsi d\u00e9cid\u00e9 de cr\u00e9er mon entreprise pour aider <strong>les collaborateurs \u00e0 \u00eatre plus heureux dans leur travail<\/strong> et leur permettre de s\u2019y \u00e9panouir<\/p>\n<p>Ce faisant, je me suis retrouv\u00e9e sur le chemin de ma qu\u00eate personnelle. En formant, accompagnant les femmes, les hommes et les structures, j\u2019ai appris sur moi, ai \u00e9t\u00e9 confront\u00e9e \u00e0 mes peurs pour d\u00e9couvrir la personne que j\u2019\u00e9tais et trouver ma juste place dans ce monde.<\/p>\n<blockquote>\n<p style=\"padding-left: 40px;\">Pour parfaire l\u2019accompagnement que j\u2019apporte, je me suis form\u00e9e \u00e0 la sophrologie aupr\u00e8s de l\u2019Ecole Alfonso Caycedo\u00a0, et au Coaching de 2008 \u00e0 2016 o\u00f9 \u00a0j\u2019ai obtenu une <strong>certification en tant que faciliteur-coach Voice Dialogue, Enn\u00e9agramme et constellations syst\u00e9miques<\/strong>. J\u2019ai de plus d\u00e9croch\u00e9 en 2017 une Accr\u00e9ditation Praticien aupr\u00e8s de l\u2019EMCC.<\/p>\n<\/blockquote>\n<p>\u00a0<\/p>\n<p>Mes accompagnements m\u2019ont donn\u00e9 l\u2019opportunit\u00e9 d\u2019en apprendre \u00e9norm\u00e9ment sur moi-m\u00eame ce qui me permet d\u2019apporter aujourd\u2019hui la richesse de cette exp\u00e9rience aux femmes et hommes qui le souhaitent, de d\u00e9buter leur chemin vers cette juste place qu\u2019ils m\u00e9ritent.<\/p>\n<p>J\u2019ai recours \u00e9galement la<strong> bio\u00e9nergie<\/strong> sur la base des enseignements de <strong>Yann Lipnick<\/strong> qui permettent un recentrage \u00e9nerg\u00e9tique et j\u2019utilise la m\u00e9thode de <strong>Grigori Grabovoi<\/strong> qui structure la conscience avec des pratiques quantiques informationnelles ; ces deux m\u00e9thodes sont compl\u00e9t\u00e9es par la m\u00e9ditation et de la relaxation.<\/p>\n<p>J\u2019accompagne aujourd\u2019hui les femmes, les hommes et les entreprises dans leur probl\u00e9matique de juste place dans le monde qui les entoure.<\/p>\n<h3 style=\"text-align: center;\">Elargissez votre conscience, agissez sur votre syst\u00e8me et<\/h3>\n<h3 style=\"text-align: center;\">reprenez votre juste place !<\/h3>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><\/p><\/blockquote>\n\n<ul class=\"wp-block-latest-posts__list wp-block-latest-posts is-layout-flow wp-block-latest-posts-is-layout-flow\"><li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/pascalinematusiak.fr\/index.php\/2021\/04\/18\/voice-dialogue-2\/\">Voice Dialogue<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/pascalinematusiak.fr\/index.php\/2021\/04\/18\/constellation-systemique-et-familiale\/\">Constellation syst\u00e9mique et familiale<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/pascalinematusiak.fr\/index.php\/2021\/04\/11\/bioenergie-et-meditation\/\">Bio\u00e9nergie et M\u00e9ditation<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Pascaline MATUSIAK \u21d2 Souhaitant m\u2019inscrire dans la lign\u00e9e familiale, je me suis initialement engag\u00e9e dans des \u00e9tudes qui m\u2019auraient conduite \u00e0 enseigner &hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-68","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/pascalinematusiak.fr\/index.php\/wp-json\/wp\/v2\/pages\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pascalinematusiak.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pascalinematusiak.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pascalinematusiak.fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pascalinematusiak.fr\/index.php\/wp-json\/wp\/v2\/comments?post=68"}],"version-history":[{"count":0,"href":"https:\/\/pascalinematusiak.fr\/index.php\/wp-json\/wp\/v2\/pages\/68\/revisions"}],"wp:attachment":[{"href":"https:\/\/pascalinematusiak.fr\/index.php\/wp-json\/wp\/v2\/media?parent=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}